{"id":10256,"date":"2021-06-23T06:27:05","date_gmt":"2021-06-23T04:27:05","guid":{"rendered":"https:\/\/www.q-software-solutions.de\/blog\/?p=10256"},"modified":"2021-06-23T09:14:06","modified_gmt":"2021-06-23T07:14:06","slug":"der-derzeit-wahrscheinlich-unbedachteste-spruch","status":"publish","type":"post","link":"https:\/\/www.q-software-solutions.de\/blog\/2021\/06\/der-derzeit-wahrscheinlich-unbedachteste-spruch\/","title":{"rendered":"Der derzeit wahrscheinlich unbedachteste Spruch,"},"content":{"rendered":"<p>den man aber immer wieder h\u00f6rt:<\/p>\n<p>&#8222;In einer endlichen Wellt kann es kein unendliches Wachstum geben&#8220;<\/p>\n<p>Das ist wohl wahr, nur wie endlich ist unsere Welt? Sie hat eine bestimmte Gr\u00f6\u00dfe und damit eine bestimme Menge an Materie. Nur ist dort drau\u00dfen ein Stern der \u00fcber 99 % der ganzen Masse unseres Planetensystems ausmacht und uns Energiemengen schickt, wir nicht mal im Milliardstel Bereich ausnutzen k\u00f6nnen. Kurz, unsere Erde ist endlich auch unser Sonnensystem ist es. F\u00fcr jeden praktischen Zweck sind aber die uns zur Verf\u00fcgung stehenden Energien unendlich.<\/p>\n<p>Dazu gilt derzeit als gesichertes Wissen:<\/p>\n<p>E = m * c\u00b2<\/p>\n<p>Kurz wir jeden praktischen Zweck bis zu Reisen ins gesamte Universum steht uns quasi unbegrenzt Energie zur Verf\u00fcgung. Die Mengen kann man berechnen, es gibt aber keine ernsthaften Grenzen. Darauf werde ich noch zur\u00fcckkommen.<\/p>\n<p>Der Weltenergiebedarf betr\u00e4gt: https:\/\/de.wikipedia.org\/wiki\/Weltenergiebedarf<\/p>\n<p>Also 574 Exajoule<br \/>\n1 Exajoule = 10 ^18 Joule<\/p>\n<p>Also schreiben wir diese Zahl aus:<\/p>\n<p>574 000 000 000 000 000 J<\/p>\n<p>Und nun schauen wir mal was nach der oben genannten Formel 1 kg Masse an Energie enth\u00e4lt, z.B. https:\/\/www.frustfrei-lernen.de\/physik\/emc2.html<\/p>\n<p>1 kg * 300 000 000 m\/s\u00b2<br \/>\ndas ergibt ausgeschrieben:<br \/>\n90000000000000000<\/p>\n<p>Und nun wir es interessant, wie viel Materie brauchen wir, um den Energiebedarf zu decken? Eine einfache Division reicht da aus<br \/>\n574 * 10 ^18 \/ 300000000 ^2 = 6377,78 kg !<\/p>\n<p>Unsere Erde hat eine ungef\u00e4hre Masse von:<\/p>\n<p>5,9723\u202f\u00b7\u202f1024<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>59723000000000000000000000 kg<\/p>\n<p>Wenn wir also unsere ganze Erde in Energie umwandelten, reichte das f\u00fcr &#8222;schlappe&#8220;<br \/>\n9.363907180934462e20 Jahre<\/p>\n<p>ausgeschrieben<br \/>\n936390718093446200000 Jahre<\/p>\n<p>Sie k\u00f6nnen unbesorgt sein, in &#8222;nur&#8220;<br \/>\n4 500 000 000 verbrennt die Sonne unsere Erde:<\/p>\n<p>Kurz, es gibt keine praktische Grenze f\u00fcr m\u00f6gliche Energie. Wie immer ist es unser begrenztes Wissen und die fehlende Anwendbarkeit um mehr zu haben, als wir je brauchen k\u00f6nnen.<\/p>\n<p>Dazu gilt der Energieerhaltungssatz:<br \/>\nhttps:\/\/de.wikipedia.org\/wiki\/Energieerhaltungssatz#Energieerhaltungssatz_in_der_Relativit%C3%A4tstheorie<\/p>\n<p>Es gibt keine praktische Grenze f\u00fcr was auch immer wir machen. Wir wandeln nur Energieformen ineinander um. Kurz, unsere Erde ist begrenzt, unsere theoretisch erreichbaren Energien sind es nicht.<\/p>\n<p>Man kann sicher davon ausgehen, da\u00df man 1945 nicht mal eine Vorstellung davon haben konnte, wie viele Menschen anno 2021 auf dieser Erde leben und sogar \u00fcberleben. Mit weiteren Wissen und mehr technischen M\u00f6glichkeiten k\u00f6nnen wir noch gewaltig viel mehr Produkte erzeugen, ohne die Erde auch zu \u00fcberfordern. Die Frage ist nur, gehen wir Wissenserwerb an oder geht es in Richtung Dogma. Mir w\u00e4re das Erstere viel lieber, aber die Sozialisten dieser Erde sind klar auf dem zweiten besch&#8230;. Weg&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>den man aber immer wieder h\u00f6rt: &#8222;In einer endlichen Wellt kann es kein unendliches Wachstum geben&#8220; Das ist wohl wahr, nur wie endlich ist unsere Welt? Sie hat eine bestimmte Gr\u00f6\u00dfe und damit eine bestimme Menge an Materie. Nur ist dort drau\u00dfen ein Stern der \u00fcber 99 % der ganzen Masse unseres Planetensystems ausmacht und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7878,7736,93,345,7932,7931,7879,20],"tags":[],"class_list":["post-10256","post","type-post","status-publish","format-standard","hentry","category-bildung","category-erziehung","category-gewalt","category-gutmenschen","category-hohn","category-koennen","category-logik","category-politik"],"_links":{"self":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/posts\/10256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/comments?post=10256"}],"version-history":[{"count":0,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/posts\/10256\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/media?parent=10256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/categories?post=10256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/tags?post=10256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}