{"id":8000,"date":"2019-09-03T06:25:49","date_gmt":"2019-09-03T04:25:49","guid":{"rendered":"https:\/\/www.q-software-solutions.de\/blog\/?p=8000"},"modified":"2019-09-22T16:52:46","modified_gmt":"2019-09-22T14:52:46","slug":"liberale-wheer-are-thou","status":"publish","type":"post","link":"https:\/\/www.q-software-solutions.de\/blog\/2019\/09\/liberale-wheer-are-thou\/","title":{"rendered":"Liberale where are thou?"},"content":{"rendered":"<p>Was reitet Sie? Warum nutzen Sie nicht die Chance liberal zu w\u00e4hlen, wenn Sie k\u00f6nnen? Warum scheinen Sie die AfD zu pr\u00e4ferieren?\u00a0 Es gibt nur eine liberale Partei in Deutschland und es ist nicht die AfD. \u00dcberlegen Sie sich was Ihnen die so stark begrenzte freie Marktwirtschaft brachte, das sollte man IMHO honorieren.<\/p>\n<p>Mal schauen ob sich dazu hier jemand \u00e4u\u00dfern wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was reitet Sie? Warum nutzen Sie nicht die Chance liberal zu w\u00e4hlen, wenn Sie k\u00f6nnen? Warum scheinen Sie die AfD zu pr\u00e4ferieren?\u00a0 Es gibt nur eine liberale Partei in Deutschland und es ist nicht die AfD. \u00dcberlegen Sie sich was Ihnen die so stark begrenzte freie Marktwirtschaft brachte, das sollte man IMHO honorieren. Mal schauen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7838,84,1709,7858,20,9,7913],"tags":[4804,7916,7914,5653,7915],"class_list":["post-8000","post","type-post","status-publish","format-standard","hentry","category-deutschland","category-freiheit","category-fud","category-liberalismus","category-politik","category-wahl","category-wohlstand","tag-afd","tag-brandenburg","tag-landtagswahlen","tag-liberale","tag-sachen"],"_links":{"self":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/posts\/8000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/comments?post=8000"}],"version-history":[{"count":0,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/posts\/8000\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/media?parent=8000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/categories?post=8000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.q-software-solutions.de\/blog\/wp-json\/wp\/v2\/tags?post=8000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}